{"id":6715,"date":"2024-10-26T14:12:52","date_gmt":"2024-10-26T14:12:52","guid":{"rendered":"https:\/\/propeep.gob.do\/noticias\/?p=6715"},"modified":"2024-10-28T14:36:18","modified_gmt":"2024-10-28T14:36:18","slug":"propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez","status":"publish","type":"post","link":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/","title":{"rendered":"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez"},"content":{"rendered":"<p>S\u00e1nchez Ram\u00edrez.- La Direcci\u00f3n General de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia (Propeep) impact\u00f3 este s\u00e1bado nuevamente la comunidad de Cotu\u00ed con un conjunto de acciones sociales y servicios que beneficiaron a miles de personas que viven en condiciones de pobreza extrema y vulnerabilidad.<\/p>\n<p>Al encabezar en este municipio la jornada de inclusi\u00f3n social \u00abPrimero T\u00fa\u00bb, el director del organismo, Roberto \u00c1ngel Salcedo, destac\u00f3 que con \u00e9sta suman tres e igual cantidad de programas \u00bb Cerca de T\u00ed\u00bb realizadas esta semana en las provincias Santo Domingo y S\u00e1nchez Ram\u00edrez, y m\u00e1s de noventa en todo el pa\u00eds.<\/p>\n<p>Resalt\u00f3 que con \u00e9stas acciones unas 10 mil personas, incluidos j\u00f3venes, adultos, envejecientes, ni\u00f1os y embarazadas, recibieron de Propeep y m\u00e1s de diez instituciones del Estado servicios, asistencias y raciones alimenticias crudas y cosidas, adem\u00e1s de prote\u00ednas.<\/p>\n<p>Como en jornadas anteriores, Roberto \u00c1ngel enfatiz\u00f3 que la gente en condiciones de vulnerabilidad y pobreza extrema est\u00e1n en el centro de las pol\u00edticas p\u00fablicas del presidente Luis Abinader, y que Cotu\u00ed y la provincia S\u00e1nchez Ram\u00edrez son de alta prioridad para el mandatario.<\/p>\n<p>\u201cEsta misi\u00f3n descentralizadora del Presidente busca que, en cada rinc\u00f3n donde sea necesario, se sienta la mano solidaria del Gobierno, y por eso estamos aqu\u00ed\u201d, manifest\u00f3 el director de Propeep.<\/p>\n<p>Agreg\u00f3 que \u201cEl presidente Luis Abinader cree firmemente en la descentralizaci\u00f3n de los poderes p\u00fablicos y en la capacidad de las entidades gubernamentales para trabajar de forma colaborativa. Por ello, es la visi\u00f3n del presidente que podamos trabajar en conjunto con los ayuntamientos y transformar \u00e1reas fundamentales de la ciudad\u201d.<\/p>\n<p>Las Jornadas<\/p>\n<p>Las jornadas de inclusi\u00f3n social \u00abPrimero T\u00fa\u00bb y \u00abCerca de T\u00ed\u00bb se desarrollaron en la Escuela Juan Ricardo Hern\u00e1ndez Polanco, del sector Los Pomos, y en<br \/>\nel Centro Educativo Victoriano Santos Hilario, de Quita Sue\u00f1o.<\/p>\n<p>M\u00e1s de 61 mil 500 metros cuadrados de arte p\u00fablico<\/p>\n<p>Roberto \u00c1ngel tambi\u00e9n entreg\u00f3 este s\u00e1bado dos \u00abPaseo de los Colores\u00bb en Cotu\u00ed con una extensi\u00f3n de 548 y 750 metros cuadrados, respectivamente, con los cuales suman m\u00e1s de 61 mil 500 metros cuadrados de arte plasmados en espacios p\u00fablicos urbanos, rescatados y rehabilitados por Propeep en barrios y municipios de todo el pa\u00eds durante su direcci\u00f3n.<\/p>\n<p>Durante los actos, el funcionario dijo que el proyecto \u00abPaseo de los Colores\u00bb tiene por objetivos rescatar, habilitar y transformar espacios p\u00fablicos junto a las alcald\u00edas municipales, para contribuir al embellecimiento, el atractivo urbano y destacar su cultura, sus actividades principales y personalidades que han contribuido a su desarrollo.<\/p>\n<p>El primer Paseo abarca una extensi\u00f3n de 750 metros cuadrados del Parque de la Salud de Villa Progreso y fue creado en homenaje al doctor H\u00e9ctor Mateo, fundador del municipio, de gran trayectoria en la medicina y que hizo grandes aportes a la comunidad y a la provincia S\u00e1nchez Ram\u00edrez.<\/p>\n<p>En \u00e9ste tambi\u00e9n se resalta el desarrollo del deporte en Cotu\u00ed.<\/p>\n<p>El segundo paseo abarca 548 metros cuadrados y fue establecido en el Liceo Francisco Henr\u00edquez y Carvajal, en el cual se destaca la historia de Cotui, la importancia de las actividades agr\u00edcolas y se hace honor a la Patria, a la cultura municipal y a personalidades que han contribuido a su desarrollo.<\/p>\n<p>Ambas obras de arte, que embellecen la urbanidad y se constituyen en un atractivo cultural y municipal, fueron plasmadas y rehabilitados los espacios de manera conjunta por Propeep y la alcald\u00eda.<\/p>\n<p>\u201cCon los paseos entregados este s\u00e1bado, completan el n\u00famero 126 que realizamos en la instituci\u00f3n durante nuestra administraci\u00f3n. M\u00e1s de 75 municipios han recibido el arte p\u00fablico como una fuente de renovaci\u00f3n urbana\u201d, precis\u00f3 el funcionario.<\/p>\n<p>El proyecto \u00abPaseo de los Colores\u00bb de Propeep, es coordinado por Lino Garc\u00eda, y dirigido por SHING Ling Ho, directora del programa Dominicana Cultural y Creativa.<\/p>\n<p>Acompa\u00f1amiento<\/p>\n<p>En S\u00e1nchez Ram\u00edrez, Roberto \u00c1ngel estuvo acompa\u00f1ado de la gobernadora provincial, Cristiana Rodr\u00edguez de Alba; el alcalde de Cotu\u00ed Jos\u00e9 Eugenio Montilla; del alcalde Benito Guerrero, del distrito Municipal Quita Sue\u00f1o-La Estancia; y Madalene D\u00edaz, directora del programa Dominicana Digna y coordinadora de las jornadas y programas sociales de Propeep, entre otras autoridades.<\/p>\n<p>Direcci\u00f3n de Comunicaciones<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e1nchez Ram\u00edrez.- La Direcci\u00f3n General de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia (Propeep) impact\u00f3 este s\u00e1bado nuevamente la comunidad de Cotu\u00ed con un conjunto de acciones sociales y servicios que beneficiaron a miles de personas que viven en condiciones de pobreza extrema y vulnerabilidad. Al encabezar en este municipio la jornada de inclusi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118,80],"tags":[],"class_list":["post-6715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cerca-de-ti","category-dominicana-digna-dd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez - Sala De Prensa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez - Sala De Prensa\" \/>\n<meta property=\"og:description\" content=\"S\u00e1nchez Ram\u00edrez.- La Direcci\u00f3n General de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia (Propeep) impact\u00f3 este s\u00e1bado nuevamente la comunidad de Cotu\u00ed con un conjunto de acciones sociales y servicios que beneficiaron a miles de personas que viven en condiciones de pobreza extrema y vulnerabilidad. Al encabezar en este municipio la jornada de inclusi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/\" \/>\n<meta property=\"og:site_name\" content=\"Sala De Prensa\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-26T14:12:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T14:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/propeep.gob.do\/noticias\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Departamento de Comunicaciones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Departamento de Comunicaciones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/\"},\"author\":{\"name\":\"Departamento de Comunicaciones\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/#\\\/schema\\\/person\\\/c5600ee02a9d3f1cbf4b2b36227fad1a\"},\"headline\":\"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez\",\"datePublished\":\"2024-10-26T14:12:52+00:00\",\"dateModified\":\"2024-10-28T14:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/\"},\"wordCount\":744,\"image\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg\",\"articleSection\":[\"Cerca de ti\",\"Dominicana Digna (DD)\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/\",\"url\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/\",\"name\":\"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez - Sala De Prensa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg\",\"datePublished\":\"2024-10-26T14:12:52+00:00\",\"dateModified\":\"2024-10-28T14:36:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/#\\\/schema\\\/person\\\/c5600ee02a9d3f1cbf4b2b36227fad1a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg\",\"contentUrl\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/\",\"name\":\"Sala De Prensa\",\"description\":\"Sigue de cerca cada noticia y evento de Propeep\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/#\\\/schema\\\/person\\\/c5600ee02a9d3f1cbf4b2b36227fad1a\",\"name\":\"Departamento de Comunicaciones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/624b773d2360b11ec53c71b63770a163f4e0c129b129abb139ef283f8a92b326?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/624b773d2360b11ec53c71b63770a163f4e0c129b129abb139ef283f8a92b326?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/624b773d2360b11ec53c71b63770a163f4e0c129b129abb139ef283f8a92b326?s=96&d=mm&r=g\",\"caption\":\"Departamento de Comunicaciones\"},\"sameAs\":[\"https:\\\/\\\/propeep.gob.do\\\/noticias\"],\"url\":\"https:\\\/\\\/propeep.gob.do\\\/noticias\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez - Sala De Prensa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/","og_locale":"es_ES","og_type":"article","og_title":"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez - Sala De Prensa","og_description":"S\u00e1nchez Ram\u00edrez.- La Direcci\u00f3n General de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia (Propeep) impact\u00f3 este s\u00e1bado nuevamente la comunidad de Cotu\u00ed con un conjunto de acciones sociales y servicios que beneficiaron a miles de personas que viven en condiciones de pobreza extrema y vulnerabilidad. Al encabezar en este municipio la jornada de inclusi\u00f3n [&hellip;]","og_url":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/","og_site_name":"Sala De Prensa","article_published_time":"2024-10-26T14:12:52+00:00","article_modified_time":"2024-10-28T14:36:18+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/propeep.gob.do\/noticias\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg","type":"image\/jpeg"}],"author":"Departamento de Comunicaciones","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Departamento de Comunicaciones","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#article","isPartOf":{"@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/"},"author":{"name":"Departamento de Comunicaciones","@id":"https:\/\/propeep.gob.do\/noticias\/#\/schema\/person\/c5600ee02a9d3f1cbf4b2b36227fad1a"},"headline":"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez","datePublished":"2024-10-26T14:12:52+00:00","dateModified":"2024-10-28T14:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/"},"wordCount":744,"image":{"@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#primaryimage"},"thumbnailUrl":"https:\/\/propeep.gob.do\/noticias\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg","articleSection":["Cerca de ti","Dominicana Digna (DD)"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/","url":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/","name":"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez - Sala De Prensa","isPartOf":{"@id":"https:\/\/propeep.gob.do\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#primaryimage"},"image":{"@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#primaryimage"},"thumbnailUrl":"https:\/\/propeep.gob.do\/noticias\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg","datePublished":"2024-10-26T14:12:52+00:00","dateModified":"2024-10-28T14:36:18+00:00","author":{"@id":"https:\/\/propeep.gob.do\/noticias\/#\/schema\/person\/c5600ee02a9d3f1cbf4b2b36227fad1a"},"breadcrumb":{"@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#primaryimage","url":"https:\/\/propeep.gob.do\/noticias\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg","contentUrl":"https:\/\/propeep.gob.do\/noticias\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-26-at-13.40.21.jpeg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/propeep.gob.do\/noticias\/propeep-revitaliza-espacios-publicos-y-promueve-la-inclusion-social-en-sanchez-ramirez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/propeep.gob.do\/noticias\/"},{"@type":"ListItem","position":2,"name":"Propeep revitaliza espacios p\u00fablicos y promueve la inclusi\u00f3n social en S\u00e1nchez Ram\u00edrez"}]},{"@type":"WebSite","@id":"https:\/\/propeep.gob.do\/noticias\/#website","url":"https:\/\/propeep.gob.do\/noticias\/","name":"Sala De Prensa","description":"Sigue de cerca cada noticia y evento de Propeep","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/propeep.gob.do\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/propeep.gob.do\/noticias\/#\/schema\/person\/c5600ee02a9d3f1cbf4b2b36227fad1a","name":"Departamento de Comunicaciones","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/624b773d2360b11ec53c71b63770a163f4e0c129b129abb139ef283f8a92b326?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/624b773d2360b11ec53c71b63770a163f4e0c129b129abb139ef283f8a92b326?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/624b773d2360b11ec53c71b63770a163f4e0c129b129abb139ef283f8a92b326?s=96&d=mm&r=g","caption":"Departamento de Comunicaciones"},"sameAs":["https:\/\/propeep.gob.do\/noticias"],"url":"https:\/\/propeep.gob.do\/noticias\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/posts\/6715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/comments?post=6715"}],"version-history":[{"count":1,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/posts\/6715\/revisions"}],"predecessor-version":[{"id":6717,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/posts\/6715\/revisions\/6717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/media\/6716"}],"wp:attachment":[{"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/media?parent=6715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/categories?post=6715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/propeep.gob.do\/noticias\/wp-json\/wp\/v2\/tags?post=6715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}